{"id":20362,"date":"2025-06-22T16:08:21","date_gmt":"2025-06-22T09:08:21","guid":{"rendered":"https:\/\/beta.sut.ac.th\/iat-csu?p=20362"},"modified":"2025-06-25T16:33:15","modified_gmt":"2025-06-25T09:33:15","slug":"%e0%b8%a5%e0%b8%87%e0%b8%9e%e0%b8%b7%e0%b9%89%e0%b8%99%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b9%80%e0%b8%84%e0%b8%a3%e0%b8%b7%e0%b8%ad%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a2%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%81-2","status":"publish","type":"post","link":"https:\/\/beta.sut.ac.th\/iat-csu\/event\/20362","title":{"rendered":"\u0e25\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23 \u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e33\u0e40\u0e20\u0e2d\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29 21 \u0e21\u0e34\u0e16\u0e38\u0e19\u0e32\u0e22\u0e19 2568"},"content":{"rendered":"<h3>\u00a0 \u00a0 \u00a0 \u0e17\u0e35\u0e21\u0e19\u0e31\u0e01\u0e27\u0e34\u0e08\u0e31\u0e22\u0e44\u0e01\u0e48\u0e42\u0e04\u0e23\u0e32\u0e0a \u0e42\u0e14\u0e22\u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23.\u0e27\u0e34\u0e17\u0e18\u0e27\u0e31\u0e0a \u0e42\u0e21\u0e2c\u0e35 \u0e19\u0e32\u0e22\u0e40\u0e09\u0e25\u0e34\u0e21\u0e0a\u0e31\u0e22 \u0e2b\u0e2d\u0e21\u0e15\u0e32 \u0e41\u0e25\u0e30\u0e17\u0e35\u0e21\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e1f\u0e32\u0e23\u0e4c\u0e21\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22 \u0e2b\u0e19\u0e48\u0e27\u0e22\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e41\u0e01\u0e48\u0e0a\u0e38\u0e21\u0e0a\u0e19 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e27\u0e34\u0e0a\u0e32\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23 \u0e25\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23 2 \u0e01\u0e25\u0e38\u0e48\u0e21 \u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23 \u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e33\u0e40\u0e20\u0e2d\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29 &gt;&gt;(1) \u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e1c\u0e39\u0e49\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e44\u0e01\u0e48\u0e42\u0e04\u0e23\u0e32\u0e0a \u0e19\u0e32\u0e22\u0e17\u0e33\u0e19\u0e2d\u0e07 \u0e1a\u0e38\u0e23\u0e32\u0e04\u0e23 \u0e1a\u0e49\u0e32\u0e19\u0e42\u0e19\u0e19\u0e2a\u0e33\u0e42\u0e23\u0e07 \u0e15\u0e33\u0e1a\u0e25\u0e01\u0e25\u0e49\u0e27\u0e22\u0e01\u0e27\u0e49\u0e32\u0e07 \u0e2d\u0e33\u0e40\u0e20\u0e2d\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\/\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 &gt;&gt; (2) \u0e01\u0e25\u0e38\u0e48\u0e21\u0e1c\u0e39\u0e49\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e44\u0e01\u0e48\u0e1e\u0e48\u0e2d\u0e41\u0e21\u0e48\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e44\u0e01\u0e48\u0e42\u0e04\u0e23\u0e32\u0e0a\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e35\u0e22\u0e4c \u0e19\u0e32\u0e22\u0e44\u0e1e\u0e11\u0e39\u0e23\u0e22\u0e4c \u0e04\u0e33\u0e1d\u0e32\u0e07 \u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e15\u0e49\u0e19\u0e41\u0e1a\u0e1a \u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e40\u0e01\u0e29\u0e15\u0e23\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e35\u0e22\u0e4c \u0e15\u0e33\u0e1a\u0e25\u0e1c\u0e31\u0e01\u0e44\u0e2b\u0e21 \u0e2d\u0e33\u0e40\u0e20\u0e2d\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e22\u0e37\u0e48\u0e19\u0e02\u0e2d\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e01\u0e32\u0e23\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e44\u0e01\u0e48\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e35\u0e22\u0e4c &gt;&gt; (3) \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e25\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e23\u0e49\u0e32\u0e19\u0e15\u0e49\u0e19\u0e41\u0e1a\u0e1a\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e44\u0e01\u0e48\u0e42\u0e04\u0e23\u0e32\u0e0a\u0e43\u0e19\u0e01\u0e32\u0e23\u0e19\u0e33\u0e44\u0e1b\u0e41\u0e1b\u0e23\u0e23\u0e39\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e01\u0e48\u0e22\u0e48\u0e32\u0e07(\u0e42\u0e04\u0e23\u0e32\u0e0a)\u0e44\u0e21\u0e49\u0e21\u0e30\u0e14\u0e31\u0e19\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e33\u0e40\u0e20\u0e2d\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29 21 \u0e21\u0e34\u0e16\u0e38\u0e19\u0e32\u0e22\u0e19 2568<\/h3>\n<h3 style=\"text-align: center\">\u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e1c\u0e39\u0e49\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e44\u0e01\u0e48\u0e42\u0e04\u0e23\u0e32\u0e0a\u0e1a\u0e49\u0e32\u0e19\u0e42\u0e19\u0e19\u0e2a\u0e33\u0e42\u0e23\u0e07<\/h3>\n<p style=\"text-align: center\"><img loading=\"lazy\" class=\"alignnone size-medium wp-image-20442\" src=\"https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_16-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_16-300x225.jpg 300w, https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_16-1024x768.jpg 1024w, https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_16-768x576.jpg 768w, https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_16-370x277.jpg 370w, https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_16.jpg 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" class=\"alignnone size-medium wp-image-20446\" src=\"https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_17-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_17-300x225.jpg 300w, https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_17-1024x768.jpg 1024w, https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_17-768x576.jpg 768w, https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_17-370x277.jpg 370w, https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_17.jpg 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" class=\"alignnone size-medium wp-image-20451\" src=\"https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_19-1-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_19-1-300x225.jpg 300w, https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_19-1-1024x768.jpg 1024w, https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_19-1-768x576.jpg 768w, https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_19-1-370x277.jpg 370w, https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_19-1.jpg 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" class=\"alignnone size-medium wp-image-20455\" src=\"https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_20-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_20-300x225.jpg 300w, https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_20-1024x768.jpg 1024w, https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_20-768x576.jpg 768w, https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_20-370x277.jpg 370w, https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_20.jpg 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" class=\"alignnone size-medium wp-image-20461\" src=\"https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_24-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_24-300x225.jpg 300w, https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_24-1024x768.jpg 1024w, https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_24-768x576.jpg 768w, https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_24-370x277.jpg 370w, https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_24.jpg 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" class=\"alignnone size-medium wp-image-20466\" src=\"https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_26-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_26-300x225.jpg 300w, https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_26-1024x768.jpg 1024w, https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_26-768x576.jpg 768w, https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_26-370x277.jpg 370w, https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_26.jpg 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<h3 style=\"text-align: center\">\u0e01\u0e25\u0e38\u0e48\u0e21\u0e1c\u0e39\u0e49\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e44\u0e01\u0e48\u0e1e\u0e48\u0e2d\u0e41\u0e21\u0e48\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e44\u0e01\u0e48\u0e42\u0e04\u0e23\u0e32\u0e0a\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e35\u0e22\u0e4c<\/h3>\n<p style=\"text-align: center\"><img loading=\"lazy\" class=\"alignnone size-medium wp-image-20479\" src=\"https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_9-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_9-300x225.jpg 300w, https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_9-1024x768.jpg 1024w, https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_9-768x576.jpg 768w, https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_9-370x277.jpg 370w, https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_9.jpg 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\u00a0<img loading=\"lazy\" class=\"alignnone size-medium wp-image-20475\" src=\"https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_8-1-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_8-1-300x225.jpg 300w, https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_8-1-1024x768.jpg 1024w, https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_8-1-768x576.jpg 768w, https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_8-1-370x277.jpg 370w, https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_8-1.jpg 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" class=\"alignnone size-medium wp-image-20484\" src=\"https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_10-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_10-300x225.jpg 300w, https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_10-1024x768.jpg 1024w, https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_10-768x576.jpg 768w, https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_10-370x277.jpg 370w, https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_10.jpg 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\u00a0<img loading=\"lazy\" class=\"alignnone size-medium wp-image-20569\" src=\"https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_43-1-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_43-1-300x225.jpg 300w, https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_43-1-1024x768.jpg 1024w, https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_43-1-768x576.jpg 768w, https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_43-1-370x277.jpg 370w, https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_43-1.jpg 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" class=\"alignnone size-medium wp-image-20488\" src=\"https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_11-1-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_11-1-300x225.jpg 300w, https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_11-1-1024x768.jpg 1024w, https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_11-1-768x576.jpg 768w, https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_11-1-370x277.jpg 370w, https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_11-1.jpg 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" class=\"alignnone size-medium wp-image-20559\" src=\"https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_38-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_38-300x225.jpg 300w, https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_38-1024x768.jpg 1024w, https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_38-768x576.jpg 768w, https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_38-370x277.jpg 370w, https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_38.jpg 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" class=\"alignnone size-medium wp-image-20545\" src=\"https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_31-1-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_31-1-300x225.jpg 300w, https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_31-1-1024x768.jpg 1024w, https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_31-1-768x576.jpg 768w, https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_31-1-370x277.jpg 370w, https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_31-1.jpg 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" class=\"alignnone size-medium wp-image-20550\" src=\"https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_32-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_32-300x225.jpg 300w, https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_32-1024x768.jpg 1024w, https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_32-768x576.jpg 768w, https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_32-370x277.jpg 370w, https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_32.jpg 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" class=\"alignnone size-medium wp-image-20554\" src=\"https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_36-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_36-300x225.jpg 300w, https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_36-1024x768.jpg 1024w, https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_36-768x576.jpg 768w, https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_36-370x277.jpg 370w, https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_36.jpg 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> \u00a0<img loading=\"lazy\" class=\"alignnone size-medium wp-image-20565\" src=\"https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_41-2-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_41-2-300x225.jpg 300w, https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_41-2-1024x768.jpg 1024w, https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_41-2-768x576.jpg 768w, https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_41-2-370x277.jpg 370w, https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_41-2.jpg 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<h3 style=\"text-align: center\">\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 (\u0e44\u0e01\u0e48\u0e42\u0e04\u0e23\u0e32\u0e0a\u0e22\u0e48\u0e32\u0e07\u0e44\u0e21\u0e49\u0e21\u0e30\u0e14\u0e31\u0e19)<\/h3>\n<p style=\"text-align: center\"><img loading=\"lazy\" class=\"alignnone size-medium wp-image-20575\" src=\"https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_1-1-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_1-1-300x225.jpg 300w, https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_1-1-1024x768.jpg 1024w, https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_1-1-768x576.jpg 768w, https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_1-1-370x277.jpg 370w, https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_1-1.jpg 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" class=\"alignnone size-medium wp-image-20586\" src=\"https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_3-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_3-300x225.jpg 300w, https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_3-1024x768.jpg 1024w, https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_3-768x576.jpg 768w, https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_3-370x277.jpg 370w, https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_3.jpg 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\u00a0<img loading=\"lazy\" class=\"alignnone size-medium wp-image-20595\" src=\"https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_29-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_29-300x225.jpg 300w, https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_29-1024x768.jpg 1024w, https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_29-768x576.jpg 768w, https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_29-370x277.jpg 370w, https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_29.jpg 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u00a0 \u00a0 \u0e17\u0e35\u0e21\u0e19\u0e31\u0e01\u0e27\u0e34\u0e08\u0e31\u0e22\u0e44\u0e01\u0e48\u0e42\u0e04\u0e23\u0e32\u0e0a \u0e42\u0e14\u0e22\u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23.\u0e27\u0e34\u0e17\u0e18 [&hellip;]<\/p>\n","protected":false},"author":183,"featured_media":20550,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5],"tags":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u0e25\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23 \u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e33\u0e40\u0e20\u0e2d\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29 21 \u0e21\u0e34\u0e16\u0e38\u0e19\u0e32\u0e22\u0e19 2568 - \u0e2b\u0e19\u0e48\u0e27\u0e22\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e41\u0e01\u0e48\u0e0a\u0e38\u0e21\u0e0a\u0e19<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/beta.sut.ac.th\/iat-csu\/event\/20362\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e25\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23 \u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e33\u0e40\u0e20\u0e2d\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29 21 \u0e21\u0e34\u0e16\u0e38\u0e19\u0e32\u0e22\u0e19 2568 - \u0e2b\u0e19\u0e48\u0e27\u0e22\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e41\u0e01\u0e48\u0e0a\u0e38\u0e21\u0e0a\u0e19\" \/>\n<meta property=\"og:description\" content=\"\u00a0 \u00a0 \u00a0 \u0e17\u0e35\u0e21\u0e19\u0e31\u0e01\u0e27\u0e34\u0e08\u0e31\u0e22\u0e44\u0e01\u0e48\u0e42\u0e04\u0e23\u0e32\u0e0a \u0e42\u0e14\u0e22\u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23.\u0e27\u0e34\u0e17\u0e18 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/beta.sut.ac.th\/iat-csu\/event\/20362\" \/>\n<meta property=\"og:site_name\" content=\"\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e41\u0e01\u0e48\u0e0a\u0e38\u0e21\u0e0a\u0e19\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-22T09:08:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-25T09:33:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_32.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/beta.sut.ac.th\/iat-csu\/#website\",\"url\":\"https:\/\/beta.sut.ac.th\/iat-csu\/\",\"name\":\"\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e41\u0e01\u0e48\u0e0a\u0e38\u0e21\u0e0a\u0e19\",\"description\":\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e27\u0e34\u0e0a\u0e32\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/beta.sut.ac.th\/iat-csu\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"th\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/beta.sut.ac.th\/iat-csu\/event\/20362#primaryimage\",\"inLanguage\":\"th\",\"url\":\"https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_32.jpg\",\"contentUrl\":\"https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_32.jpg\",\"width\":1280,\"height\":960},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/beta.sut.ac.th\/iat-csu\/event\/20362#webpage\",\"url\":\"https:\/\/beta.sut.ac.th\/iat-csu\/event\/20362\",\"name\":\"\u0e25\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23 \u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e33\u0e40\u0e20\u0e2d\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29 21 \u0e21\u0e34\u0e16\u0e38\u0e19\u0e32\u0e22\u0e19 2568 - \u0e2b\u0e19\u0e48\u0e27\u0e22\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e41\u0e01\u0e48\u0e0a\u0e38\u0e21\u0e0a\u0e19\",\"isPartOf\":{\"@id\":\"https:\/\/beta.sut.ac.th\/iat-csu\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/beta.sut.ac.th\/iat-csu\/event\/20362#primaryimage\"},\"datePublished\":\"2025-06-22T09:08:21+00:00\",\"dateModified\":\"2025-06-25T09:33:15+00:00\",\"author\":{\"@id\":\"https:\/\/beta.sut.ac.th\/iat-csu\/#\/schema\/person\/1a1da4aae863e250b51355b3d53c6741\"},\"breadcrumb\":{\"@id\":\"https:\/\/beta.sut.ac.th\/iat-csu\/event\/20362#breadcrumb\"},\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/beta.sut.ac.th\/iat-csu\/event\/20362\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/beta.sut.ac.th\/iat-csu\/event\/20362#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/beta.sut.ac.th\/iat-csu\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e25\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23 \u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e33\u0e40\u0e20\u0e2d\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29 21 \u0e21\u0e34\u0e16\u0e38\u0e19\u0e32\u0e22\u0e19 2568\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/beta.sut.ac.th\/iat-csu\/#\/schema\/person\/1a1da4aae863e250b51355b3d53c6741\",\"name\":\"Admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/beta.sut.ac.th\/iat-csu\/#personlogo\",\"inLanguage\":\"th\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/18247569b8f035ca3300d94556917544?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/18247569b8f035ca3300d94556917544?s=96&d=mm&r=g\",\"caption\":\"Admin\"},\"url\":\"https:\/\/beta.sut.ac.th\/iat-csu\/author\/medwadee\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e25\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23 \u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e33\u0e40\u0e20\u0e2d\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29 21 \u0e21\u0e34\u0e16\u0e38\u0e19\u0e32\u0e22\u0e19 2568 - \u0e2b\u0e19\u0e48\u0e27\u0e22\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e41\u0e01\u0e48\u0e0a\u0e38\u0e21\u0e0a\u0e19","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/beta.sut.ac.th\/iat-csu\/event\/20362","og_locale":"th_TH","og_type":"article","og_title":"\u0e25\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23 \u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e33\u0e40\u0e20\u0e2d\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29 21 \u0e21\u0e34\u0e16\u0e38\u0e19\u0e32\u0e22\u0e19 2568 - \u0e2b\u0e19\u0e48\u0e27\u0e22\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e41\u0e01\u0e48\u0e0a\u0e38\u0e21\u0e0a\u0e19","og_description":"\u00a0 \u00a0 \u00a0 \u0e17\u0e35\u0e21\u0e19\u0e31\u0e01\u0e27\u0e34\u0e08\u0e31\u0e22\u0e44\u0e01\u0e48\u0e42\u0e04\u0e23\u0e32\u0e0a \u0e42\u0e14\u0e22\u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23.\u0e27\u0e34\u0e17\u0e18 [&hellip;]","og_url":"https:\/\/beta.sut.ac.th\/iat-csu\/event\/20362","og_site_name":"\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e41\u0e01\u0e48\u0e0a\u0e38\u0e21\u0e0a\u0e19","article_published_time":"2025-06-22T09:08:21+00:00","article_modified_time":"2025-06-25T09:33:15+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_32.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Written by":"Admin"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/beta.sut.ac.th\/iat-csu\/#website","url":"https:\/\/beta.sut.ac.th\/iat-csu\/","name":"\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e41\u0e01\u0e48\u0e0a\u0e38\u0e21\u0e0a\u0e19","description":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e27\u0e34\u0e0a\u0e32\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e01\u0e32\u0e23\u0e40\u0e01\u0e29\u0e15\u0e23","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/beta.sut.ac.th\/iat-csu\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"th"},{"@type":"ImageObject","@id":"https:\/\/beta.sut.ac.th\/iat-csu\/event\/20362#primaryimage","inLanguage":"th","url":"https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_32.jpg","contentUrl":"https:\/\/beta.sut.ac.th\/iat-csu\/wp-content\/uploads\/sites\/199\/2025\/06\/LINE_ALBUM_\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19-\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29-21-\u0e21\u0e34\u0e22-68_250623_32.jpg","width":1280,"height":960},{"@type":"WebPage","@id":"https:\/\/beta.sut.ac.th\/iat-csu\/event\/20362#webpage","url":"https:\/\/beta.sut.ac.th\/iat-csu\/event\/20362","name":"\u0e25\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23 \u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e33\u0e40\u0e20\u0e2d\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29 21 \u0e21\u0e34\u0e16\u0e38\u0e19\u0e32\u0e22\u0e19 2568 - \u0e2b\u0e19\u0e48\u0e27\u0e22\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e41\u0e01\u0e48\u0e0a\u0e38\u0e21\u0e0a\u0e19","isPartOf":{"@id":"https:\/\/beta.sut.ac.th\/iat-csu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/beta.sut.ac.th\/iat-csu\/event\/20362#primaryimage"},"datePublished":"2025-06-22T09:08:21+00:00","dateModified":"2025-06-25T09:33:15+00:00","author":{"@id":"https:\/\/beta.sut.ac.th\/iat-csu\/#\/schema\/person\/1a1da4aae863e250b51355b3d53c6741"},"breadcrumb":{"@id":"https:\/\/beta.sut.ac.th\/iat-csu\/event\/20362#breadcrumb"},"inLanguage":"th","potentialAction":[{"@type":"ReadAction","target":["https:\/\/beta.sut.ac.th\/iat-csu\/event\/20362"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/beta.sut.ac.th\/iat-csu\/event\/20362#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/beta.sut.ac.th\/iat-csu"},{"@type":"ListItem","position":2,"name":"\u0e25\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23 \u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e33\u0e40\u0e20\u0e2d\u0e2b\u0e49\u0e27\u0e22\u0e17\u0e31\u0e1a\u0e17\u0e31\u0e19 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e28\u0e23\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e29 21 \u0e21\u0e34\u0e16\u0e38\u0e19\u0e32\u0e22\u0e19 2568"}]},{"@type":"Person","@id":"https:\/\/beta.sut.ac.th\/iat-csu\/#\/schema\/person\/1a1da4aae863e250b51355b3d53c6741","name":"Admin","image":{"@type":"ImageObject","@id":"https:\/\/beta.sut.ac.th\/iat-csu\/#personlogo","inLanguage":"th","url":"https:\/\/secure.gravatar.com\/avatar\/18247569b8f035ca3300d94556917544?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/18247569b8f035ca3300d94556917544?s=96&d=mm&r=g","caption":"Admin"},"url":"https:\/\/beta.sut.ac.th\/iat-csu\/author\/medwadee"}]}},"_links":{"self":[{"href":"https:\/\/beta.sut.ac.th\/iat-csu\/wp-json\/wp\/v2\/posts\/20362"}],"collection":[{"href":"https:\/\/beta.sut.ac.th\/iat-csu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/beta.sut.ac.th\/iat-csu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/beta.sut.ac.th\/iat-csu\/wp-json\/wp\/v2\/users\/183"}],"replies":[{"embeddable":true,"href":"https:\/\/beta.sut.ac.th\/iat-csu\/wp-json\/wp\/v2\/comments?post=20362"}],"version-history":[{"count":5,"href":"https:\/\/beta.sut.ac.th\/iat-csu\/wp-json\/wp\/v2\/posts\/20362\/revisions"}],"predecessor-version":[{"id":20608,"href":"https:\/\/beta.sut.ac.th\/iat-csu\/wp-json\/wp\/v2\/posts\/20362\/revisions\/20608"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/beta.sut.ac.th\/iat-csu\/wp-json\/wp\/v2\/media\/20550"}],"wp:attachment":[{"href":"https:\/\/beta.sut.ac.th\/iat-csu\/wp-json\/wp\/v2\/media?parent=20362"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/beta.sut.ac.th\/iat-csu\/wp-json\/wp\/v2\/categories?post=20362"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/beta.sut.ac.th\/iat-csu\/wp-json\/wp\/v2\/tags?post=20362"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}